{"id":176,"date":"2021-02-17T16:23:53","date_gmt":"2021-02-17T19:23:53","guid":{"rendered":"http:\/\/abrapalabraediciones.com\/?page_id=176"},"modified":"2021-02-23T10:58:52","modified_gmt":"2021-02-23T13:58:52","slug":"editamos-tu-libro","status":"publish","type":"page","link":"https:\/\/abrapalabraediciones.com\/index.php\/editamos-tu-libro\/","title":{"rendered":"Editamos tu libro"},"content":{"rendered":"<body>\n<p>Editar un libro es un proceso que lleva varios pasos.<br>Te ofrecemos acompa\u00f1arte en cada uno de ellos.<br><br>A continuaci\u00f3n te contamos los pasos, necesarios a nuestro criterio, para editar tu libro:<\/p>\n\n\n\n<p><strong>(1)<\/strong> <strong>Lectura del material e informe del trabajo de edici\u00f3n que necesita el texto seg\u00fan nuestro criterio<\/strong><br>Antes que nada, leemos el material. Eso implica que t\u00fa nos lo env\u00edes. No te preocupes que no nos interesa robarle nada a nadie. Conf\u00eda en que vamos a respetar la privacidad de tu material y tu derecho de autor sobre el mismo. Lo vamos a declarar expresamente por mail al momento de acusar recibo de tu material. Del mismo modo confiamos en la declaraci\u00f3n de autor\u00eda que te vamos a solicitar cuando nos env\u00edes el material.<br>La lectura del material se hace con el fin de evaluar el tipo de trabajo necesario sobre el texto desde un punto de vista que incluye el uso del lenguaje y la limpieza tipogr\u00e1fica. No es el objetivo primario de esta lectura el opinar sobre su calidad en cuanto al contenido expresado por el texto.<br>En base a la lectura vamos a generar un informe sobre el tipo de trabajo que necesita tu texto.<br><\/p>\n\n\n\n<p><strong>(2) Trabajo de edici\u00f3n sobre el texto<\/strong><br>En el informe de lectura te vamos a sugerir diferentes tipos de trabajo de edici\u00f3n que puede necesitar tu texto:<br><strong>Edici\u00f3n simple<\/strong>. Una revisi\u00f3n de estilo (ortograf\u00eda, errores de tipeo, errores comunes, etc.) y una limpieza del texto para su posterior diagramado en formato libro (espacios de m\u00e1s, tabuladores incorrectos, formateos incorrectos, etc.).<br><strong>Edici\u00f3n creativa<\/strong>. Puede que tu texto necesite ser reescrito en su totalidad o en muchas partes, a los efectos de que sea m\u00e1s legible y de que exprese de forma m\u00e1s clara su contenido. En ese caso una opci\u00f3n es la edici\u00f3n creativa del texto por parte de uno de nuestros editores que sea hace cargo de su reescritura.<br><strong>Autoedici\u00f3n con tutor\u00eda<\/strong>. Si tu texto necesita reescritura, puede que te propongamos que t\u00fa mismo hagas el trabajo con la tutor\u00eda de uno de nuestros editores. De ser este el caso, el mismo informe te va a explicar cu\u00e1l es la metodolog\u00eda de trabajo de la tutor\u00eda que te proponemos. Luego del trabajo de autoedici\u00f3n siempre vamos a hacer un trabajo de \u00abEdici\u00f3n simple\u00bb.<br><\/p>\n\n\n\n<p><strong>(3) Maquetaci\u00f3n y dise\u00f1o de tapa<\/strong><br>Para poder publicar tu libro en formato papel o digital, es necesario diagramar el texto, dise\u00f1ar una tapa y elaborar los originales para imprenta o el libro digital base. Para el dise\u00f1o de tapa vamos a tomar en cuenta tus ideas y preferencias.<br><\/p>\n\n\n\n<p><strong>(4)<\/strong> <strong>Publicaci\u00f3n en formato papel<\/strong><br>Dependiendo de la extensi\u00f3n de tu libro, te vamos a ofrecer distintas opciones de publicaci\u00f3n en formato papel: tiraje reducido formato semi-artesanal (hasta 50 ejemplares), tiraje en imprenta especializada en libro (m\u00ednimo 100 ejemplares).<br><\/p>\n\n\n\n<p><strong>(5)<\/strong> <strong>Publicaci\u00f3n en formato digital<\/strong><br>Te proveemos del original para que puedas vender tu libro en formato digital en las tiendas especializadas (Amazon, Fnac, Casa de Libro, etc.), o en el sitio que t\u00fa quieras.<br><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>Editor responsable<\/strong>\n\nAbrapalabra ediciones: <strong>Carlos G\u00f3mez Guerrero<\/strong>\n\nColecci\u00f3n \u00abPiedra en el charco\u00bb: <strong>Marco Algorta<\/strong>\n<\/pre>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>Editar un libro es un proceso que lleva varios pasos.Te ofrecemos acompa\u00f1arte en cada uno de ellos. A continuaci\u00f3n te contamos los pasos, necesarios a nuestro criterio, para editar tu libro: (1) Lectura del material e informe del trabajo de edici\u00f3n que necesita el texto seg\u00fan nuestro criterioAntes que nada, leemos el material. Eso implica &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/abrapalabraediciones.com\/index.php\/editamos-tu-libro\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Editamos tu libro&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_joinchat":[],"footnotes":""},"class_list":["post-176","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/pages\/176"}],"collection":[{"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":8,"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/pages\/176\/revisions"}],"predecessor-version":[{"id":266,"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/pages\/176\/revisions\/266"}],"wp:attachment":[{"href":"https:\/\/abrapalabraediciones.com\/index.php\/wp-json\/wp\/v2\/media?parent=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}